{"id":132046,"date":"2016-03-04T00:00:00","date_gmt":"2016-03-04T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/"},"modified":"2024-07-30T19:28:57","modified_gmt":"2024-07-30T19:28:57","slug":"grantet-institucionale-per-organizatat-e-shoqerise-civile","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/","title":{"rendered":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE"},"content":{"rendered":"<p>\n\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-4.jpg\" style=\"width: 640px; height: 360px;\" \/><\/p>\n<p>\n\tQendra rajonale p\u00ebr mjedisin jet\u00ebsor (REC), Zyra n\u00eb Serbi, shpall\u00eb ftes\u00ebn p\u00ebr dor\u00ebzimin e paraqitjeve p\u00ebr grantin institucional p\u00ebr t\u00eb gjith\u00eb organizatat e interesuara t\u00eb shoq\u00ebris\u00eb civile nga Serbia t\u00eb cilat merren me mbrojtjn e mjediseve jet\u00ebsore dhe zhvillimit t\u00eb q\u00ebndruesh\u00ebm.<\/p>\n<p>\n\tGrantet institucionale ndahen n\u00eb kuad\u00ebr t\u00eb Programit mb\u00ebshtet\u00ebs t\u00eb shoq\u00ebrive civile n\u00eb Serbi, i cili realizohet nga zyra e REC-it n\u00eb Serbi, p\u00ebrmes ndihm\u00ebs finansiare t\u00eb Agjensionit Suedez p\u00ebr bashk\u00ebpunim dhe zhvillim nd\u00ebrkomb\u00ebtar (SIDA).<\/p>\n<p>\n\tProgrami ka p\u00ebr q\u00ebllim t\u00eb forcoj shoq\u00ebrit\u00eb civile q\u00eb n\u00eb m\u00ebnyr\u00eb efikase, aktive dhe sensitive t\u00eb participoj n\u00eb procesin e marrjes s\u00eb vendimeve dhe krijimin e politikave n\u00eb fush\u00ebn e mjediseve jet\u00ebsore, t\u00eb marr\u00eb pjes\u00ebmarrje aktive n\u00eb procesin e integrimeve europiane t\u00eb Serbis\u00eb dhe n\u00eb m\u00ebnyr\u00eb aktive t\u00eb p\u00ebrcjell procesin e realizimit t\u00eb politkave n\u00eb nivelin lokal, rajonal dhe nacional.<\/p>\n<p>\n\tOrganizatat e shoq\u00ebris\u00eb civile me seli n\u00eb Republik\u00ebn e Serbis\u00eb ftohen q\u00eb t\u00eb paraqiten p\u00ebr k\u00ebt\u00eb p\u00ebrkrahje ekstenzive dhe n\u00ebse zgjidhen do t\u00eb b\u00ebhen p\u00ebrdorues t\u00eb p\u00ebrkrahjen finansiare p\u00ebr fuqizimin institucional t\u00eb organizatava n\u00eb fush\u00ebn e zhvillimit t\u00eb q\u00ebndruesh\u00ebm dhe mbrojtjen e mjedisit jet\u00ebsor, por edhe programit special t\u00eb dizajnuar t\u00eb zhvillimit t\u00eb kapaciteteve dhe avansimit t\u00eb aft\u00ebsive dhe diturive n\u00eb shum\u00eb fusha. Organizatat e zgjedhura, gjithashtu, do t\u00eb marrin p\u00ebr detyr\u00eb organizimin e rrjetit OCD-s\u00eb dhe vendosjen e platform\u00ebs p\u00ebr dialog me sektorin e qeveris\u00eb.<\/p>\n<p>\n\tN\u00eb kuad\u00ebr t\u00eb k\u00ebtij programi trevje\u00e7ar \u00ebsht\u00eb siguruar buxhet prej 800.000 euroave p\u00ebr p\u00ebrkrahje direkte t\u00eb fuqizimit institucional t\u00eb OCD-s\u00eb, p\u00ebrmes granteve t\u00eb ndara n\u00eb dy ftesa nga 400.000 euro. Shuma maksimale e grantit individual \u00ebsht\u00eb 45.000 euro.<\/p>\n<p>\n\tKonkursi p\u00ebr ndarjen e granteve institucionale realizohet n\u00eb dy faza. N\u00eb faz\u00ebn e par\u00eb t\u00eb gjith\u00eb orgazitat e interesuara mund t\u00eb paraqiten duke dor\u00ebzuar paraqitjet elektoronike, Deklaratat mbi interesimim. Faza e dyt\u00eb e konkursit fillon me zgjedhjen e ngusht\u00eb t\u00eb organizatave t\u00eb cilat do t\u00eb ftohen q\u00eb t`i dor\u00ebzojn\u00eb aplikacionet komplete.<\/p>\n<p>\n\tJu lusim q\u00eb para sjelljes s\u00eb vendimit p\u00ebr paraqitje n\u00eb k\u00ebt\u00eb konkurs ta lexoni tekstin e Ftes\u00ebs dhe t\u00eb gjith\u00eb dokumentacionin p\u00ebrcjell\u00ebs me udh\u00ebzimet t\u00eb cilat jan\u00eb t\u00eb bashkangjitura n\u00eb tekst, n\u00eb m\u00ebnyr\u00eb q\u00eb t\u00eb njiheni me kushtet dhe procedur\u00ebn p\u00ebr ndarjen e granteve institucionale. Deklarat\u00ebn rreth interesesimit t\u00eb plot\u00ebsuar n\u00eb m\u00ebnyr\u00eb t\u00eb sakt\u00eb (n\u00eb gjuh\u00ebn serbe dhe angleze) dor\u00ebzojeni p\u00ebrmes adres\u00ebs elektronike <a href=\"mailto:office.coserbia@rec.org\">office.coserbia@rec.org<\/a>,, m\u00eb s\u00eb voni deri m\u00eb 14 mars, ora 13. Paraqitjet t\u00eb cilat arrijn\u00eb pas afatit t\u00eb caktuar nuk do t\u00eb merren n\u00eb shqyrtim.\u00a0<\/p>\n<p>\n\t<strong>Dokumentacionin p\u00ebrcjell\u00ebs mund ta gjeni k\u00ebtu <\/strong><a href=\"http:\/\/serbia.rec.org\/news\/19\/23\/Institucionalni-grantovi-za-organizacije-civilnog-drustva.html\">http:\/\/serbia.rec.org\/news\/19\/23\/Institucionalni-grantovi-za-organizacije-civilnog-drustva.html<\/a><\/p>\n<p>\n\t<strong>Burimi: Qendra rajonale p\u00ebr mjedisin jet\u00ebsor (REC), Zyra n\u00eb Serbi dhe Trupi Koordinues \u00a0<\/strong><\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qendra rajonale p\u00ebr mjedisin jet\u00ebsor (REC), Zyra n\u00eb Serbi, shpall\u00eb ftes\u00ebn p\u00ebr dor\u00ebzimin e paraqitjeve p\u00ebr grantin institucional p\u00ebr t\u00eb gjith\u00eb organizatat e interesuara t\u00eb shoq\u00ebris\u00eb civile nga Serbia t\u00eb cilat merren me mbrojtjn e mjediseve jet\u00ebsore dhe zhvillimit t\u00eb q\u00ebndruesh\u00ebm\u2026<\/p>\n","protected":false},"author":1,"featured_media":132051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-132046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Qendra rajonale p\u00ebr mjedisin jet\u00ebsor (REC), Zyra n\u00eb Serbi, shpall\u00eb ftes\u00ebn p\u00ebr dor\u00ebzimin e paraqitjeve p\u00ebr grantin institucional p\u00ebr t\u00eb gjith\u00eb organizatat e interesuara t\u00eb shoq\u00ebris\u00eb civile nga Serbia t\u00eb cilat merren me mbrojtjn e mjediseve jet\u00ebsore dhe zhvillimit t\u00eb q\u00ebndruesh\u00ebm...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-04T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:28:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE\",\"datePublished\":\"2016-03-04T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:28:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/\"},\"wordCount\":699,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1457099819_news_pic04032016_2v-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/\",\"name\":\"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1457099819_news_pic04032016_2v-5.jpg\",\"datePublished\":\"2016-03-04T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:28:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1457099819_news_pic04032016_2v-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1457099819_news_pic04032016_2v-5.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/grantet-institucionale-per-organizatat-e-shoqerise-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/","og_locale":"sq_AL","og_type":"article","og_title":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Qendra rajonale p\u00ebr mjedisin jet\u00ebsor (REC), Zyra n\u00eb Serbi, shpall\u00eb ftes\u00ebn p\u00ebr dor\u00ebzimin e paraqitjeve p\u00ebr grantin institucional p\u00ebr t\u00eb gjith\u00eb organizatat e interesuara t\u00eb shoq\u00ebris\u00eb civile nga Serbia t\u00eb cilat merren me mbrojtjn e mjediseve jet\u00ebsore dhe zhvillimit t\u00eb q\u00ebndruesh\u00ebm...","og_url":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2016-03-04T00:00:00+00:00","article_modified_time":"2024-07-30T19:28:57+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE","datePublished":"2016-03-04T00:00:00+00:00","dateModified":"2024-07-30T19:28:57+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/"},"wordCount":699,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/","url":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/","name":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg","datePublished":"2016-03-04T00:00:00+00:00","dateModified":"2024-07-30T19:28:57+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1457099819_news_pic04032016_2v-5.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/grantet-institucionale-per-organizatat-e-shoqerise-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"GRANTET INSTITUCIONALE P\u00cbR ORGANIZATAT E SHOQ\u00cbRIS\u00cb CIVILE"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/132046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=132046"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/132046\/revisions"}],"predecessor-version":[{"id":132050,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/132046\/revisions\/132050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/132051"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=132046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=132046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=132046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}