{"id":128664,"date":"2016-12-01T00:00:00","date_gmt":"2016-12-01T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/"},"modified":"2024-07-30T19:23:15","modified_gmt":"2024-07-30T19:23:15","slug":"ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/","title":{"rendered":"N\u00cb BUJANOC  \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d"},"content":{"rendered":"<p>\n\t<strong><img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-4.jpg\" style=\"width: 315px; height: 230px; float: left;\" \/><\/strong><strong>Bujanoc \u2013<\/strong> Me ligjerat\u00ebn \u201cEurop\u00eb, ajo je ti\u201d, e cila \u00ebsht\u00eb mbajtur n\u00eb Paralelen e Fakultetit t\u00eb Subotic\u00ebs n\u00eb Bujanoc, \u00ebsht\u00eb sh\u00ebnuar fillimi i kampanj\u00ebs po me t\u00eb njejtin em\u00ebr. Kjo ligjerat\u00eb \u00ebsht\u00eb nj\u00ebra nd\u00ebr ngjarjen t\u00eb cilat gjat\u00eb kampanj\u00ebs do t\u00eb organizohen n\u00eb 34 komuna programore n\u00eb m\u00ebnyr\u00eb q\u00eb t\u00eb rinj\u00ebt t\u00eb zgj\u00ebrojn\u00eb diturit\u00eb mbi procesin e integrimeve europiane dhe t\u00eb njohin t\u00eb gjitha mund\u00ebsit\u00eb t\u00eb cil\u00ebt integrimet ofrojn\u00eb, dhe t\u00eb cilat n\u00eb m\u00ebnyr\u00eb pozitive ndikojn\u00eb n\u00eb zhvillimn e tyre personal, si\u00e7 \u00ebsht\u00eb vullnetarizmi n\u00eb vendet e UE-s\u00eb, program i studimeve, bursave dhe shk\u00ebmbimit.<\/p>\n<p>\n\tKampanj\u00ebn \u201cEurop\u00eb, ajo je ti\u201d, e financon UE-ja, Qeveria e Zvicrr\u00ebs dhe Qeveria e Republik\u00ebs s\u00eb Serbis\u00eb p\u00ebrmes programit zhvillimor t\u00eb Progresit Europian me q\u00ebllim q\u00eb procesi i integrimeve europiane t`i ofrohet qytetar\u00ebve, p\u00ebrkat\u00ebsisht t\u00eb rinj\u00ebve n\u00eb Serbin\u00eb juglindore dhe jugperendimore.<\/p>\n<p>\n\t\u201eM\u00eb shum\u00eb se 70% e t\u00eb rinj\u00ebve nuk kan\u00eb udh\u00ebtuar jasht\u00eb kufijve t\u00eb Serbis\u00eb, af\u00ebr 50% jan\u00eb t\u00eb papun\u00eb dhe vet\u00ebm 10% t\u00eb popullat\u00ebs s\u00eb p\u00ebrgjithshme jan\u00eb me arsim t\u00eb lart\u00eb. N\u00eb k\u00ebto sfida i p\u00ebrgjigjen programet e UE-s\u00eb, para s\u00ebgjithash t\u00eb Erazmus Plus dhe Servisit t\u00eb Vullnetar\u00ebve Europian, nd\u00ebrsa d\u00ebshira jon\u00eb \u00ebsht\u00eb q\u00eb t\u00eb rinj\u00ebt t`ua ofrojm\u00eb UE-n\u00eb, mund\u00ebsit\u00eb p\u00ebr studime, si edhe shk\u00ebmbimet dhe inkurajimin e p\u00ebrvoj\u00ebs s\u00eb pun\u00ebs n\u00eb nj\u00ebrin nd\u00ebr vendet an\u00ebtare t\u00eb UE-s\u00eb. P\u00ebrvoajt dhe diturit e arritura n\u00eb k\u00ebt\u00eb m\u00ebnyr\u00eb m\u00eb von\u00eb i mund\u00ebsojn\u00eb pun\u00eb m\u00eb t\u00eb mir\u00eb dhe jet\u00eb m\u00eb kualitative\u201d, ka thn\u00eb gjat\u00eb ligj\u00ebrimit Naim Leo Beshiri, drejtori egzekutues i Institutit p\u00ebr Pun\u00eb Europiane dhe an\u00ebtari i Ekipit t\u00eb Serbis\u00eb dhe Europ\u00ebs.\u00a0<\/p>\n<p>\n\tDuke folur mbi k\u00ebt\u00eb njer\u00ebz e ri mund t\u00eb njoftohen p\u00ebr mund\u00ebsit\u00eb t\u00eb cilat inegrimet i ofrojn\u00eb, Jovana Bozhi\u00e7koviq nga Shkolla e Hapur e Beogradit ka th\u00ebn\u00eb: \u201cNj\u00ebra nd\u00ebr m\u00ebnyrat e af\u00ebrsimit t\u00eb UE-s\u00eb p\u00ebr qytetar\u00ebt, p\u00ebrkat\u00ebsisht t\u00eb t\u00eb rinj\u00ebve, \u00ebsht\u00eb aplikacioni \u201cEuropa p\u00ebr me vete.\u201d Aplikacioni ofron pasqyr t\u00eb informacioneve rreth mund\u00ebsive t\u00eb cilat UE-ja i ofron t\u00eb rinj\u00ebve n\u00eb aspektin e arsimit, vullnetarizmit, udh\u00ebtimit dhe pun\u00ebs n\u00eb UE, gj\u00eb q\u00eb \u00ebsht\u00eb e r\u00ebnd\u00ebsishme edhe p\u00ebr t\u00eb rinj\u00ebt n\u00eb Bujanoc\u201d.<\/p>\n<p>\n\tN\u00eb m\u00ebnyr\u00eb q\u00eb sa m\u00eb shum\u00eb t\u00eb rinj t\u00eb zgj\u00ebrojn\u00eb t\u00eb njohurit mbi procesin e integrimeve europiane dhe t\u00eb dijn\u00eb t\u00eb gjitha rreth mund\u00ebsive t\u00eb cilat ofrojn\u00eb integrimet, po e njejt\u00eb ligjerat\u00eb do t\u00eb mbahet n\u00eb Universitetin e Novi Pazarit.<\/p>\n<p>\n\tP\u00ebrmes shum\u00eb aktiviteteve dhe ngjarjeve n\u00eb juglindje dhe jugperendim t\u00eb Serbis\u00eb, deri n\u00eb qershor 2017, n\u00eb kuad\u00ebr t\u00eb kampanj\u00ebs t\u00eb cilat i realizon Fondacioni p\u00ebr Komunikime t\u00eb Reja Dokukino dhe Olaf&McAteer, t\u00eb rinj\u00ebt dhe popullata e p\u00ebrgjitshme do t\u00eb ken\u00eb mund\u00ebsi q\u00eb t\u00eb njohin m\u00eb shum\u00eb mbi procesin e integrimeve europiane si edhe t\u00eb informohen mbi mund\u00ebsit\u00eb t\u00eb pjes\u00ebmarrjes s\u00eb tyre aktive n\u00eb k\u00ebt\u00eb proces dhe mbi mund\u00ebsit\u00eb t\u00eb cilat integrimet i ofrojn\u00eb, nd\u00ebrsa t\u00eb cilat pozitivisht ndikojn\u00eb n\u00eb zhvillimin e tyre personal, por edhe n\u00eb zhvillimin e bashk\u00ebsive t\u00eb tyre.<\/p>\n<p>\n\t<strong>Burimi: Jugpres dhe Trupi Koordinues\u00a0<\/strong><\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bujanoc \u2013\u00a0Me ligjerat\u00ebn \u201cEurop\u00eb, ajo je ti\u201d, e cila \u00ebsht\u00eb mbajtur n\u00eb Paralelen e Fakultetit t\u00eb Subotic\u00ebs n\u00eb Bujanoc, \u00ebsht\u00eb sh\u00ebnuar fillimi i kampanj\u00ebs po me t\u00eb njejtin em\u00ebr. Kjo ligjerat\u00eb \u00ebsht\u00eb nj\u00ebra nd\u00ebr ngjarjen t\u00eb cilat gjat\u00eb kampanj\u00ebs do t\u00eb organizohen n\u00eb 34 komuna programore n\u00eb m\u00ebnyr\u00eb q\u00eb t\u00eb rinj\u00ebt t\u00eb zgj\u00ebrojn\u00eb diturit\u00eb mbi procesin\u2026<\/p>\n","protected":false},"author":1,"featured_media":128669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-128664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Bujanoc \u2013\u00a0Me ligjerat\u00ebn \u201cEurop\u00eb, ajo je ti\u201d, e cila \u00ebsht\u00eb mbajtur n\u00eb Paralelen e Fakultetit t\u00eb Subotic\u00ebs n\u00eb Bujanoc, \u00ebsht\u00eb sh\u00ebnuar fillimi i kampanj\u00ebs po me t\u00eb njejtin em\u00ebr. Kjo ligjerat\u00eb \u00ebsht\u00eb nj\u00ebra nd\u00ebr ngjarjen t\u00eb cilat gjat\u00eb kampanj\u00ebs do t\u00eb organizohen n\u00eb 34 komuna programore n\u00eb m\u00ebnyr\u00eb q\u00eb t\u00eb rinj\u00ebt t\u00eb zgj\u00ebrojn\u00eb diturit\u00eb mbi procesin...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-01T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:23:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d\",\"datePublished\":\"2016-12-01T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:23:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/\"},\"wordCount\":851,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1480593597_news_pic_01122016_1-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/\",\"name\":\"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1480593597_news_pic_01122016_1-5.jpg\",\"datePublished\":\"2016-12-01T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:23:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1480593597_news_pic_01122016_1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1480593597_news_pic_01122016_1-5.jpg\",\"width\":315,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/","og_locale":"sq_AL","og_type":"article","og_title":"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Bujanoc \u2013\u00a0Me ligjerat\u00ebn \u201cEurop\u00eb, ajo je ti\u201d, e cila \u00ebsht\u00eb mbajtur n\u00eb Paralelen e Fakultetit t\u00eb Subotic\u00ebs n\u00eb Bujanoc, \u00ebsht\u00eb sh\u00ebnuar fillimi i kampanj\u00ebs po me t\u00eb njejtin em\u00ebr. Kjo ligjerat\u00eb \u00ebsht\u00eb nj\u00ebra nd\u00ebr ngjarjen t\u00eb cilat gjat\u00eb kampanj\u00ebs do t\u00eb organizohen n\u00eb 34 komuna programore n\u00eb m\u00ebnyr\u00eb q\u00eb t\u00eb rinj\u00ebt t\u00eb zgj\u00ebrojn\u00eb diturit\u00eb mbi procesin...","og_url":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2016-12-01T00:00:00+00:00","article_modified_time":"2024-07-30T19:23:15+00:00","og_image":[{"width":315,"height":230,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d","datePublished":"2016-12-01T00:00:00+00:00","dateModified":"2024-07-30T19:23:15+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/"},"wordCount":851,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/","url":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/","name":"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg","datePublished":"2016-12-01T00:00:00+00:00","dateModified":"2024-07-30T19:23:15+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1480593597_news_pic_01122016_1-5.jpg","width":315,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/ne-bujanoc-eshte-shenuar-fillimi-i-kampanjes-europe-ajo-je-ti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"N\u00cb BUJANOC \u00cbSHT\u00cb SH\u00cbNUAR FILLIMI I KAMPANJ\u00cbS \u201cEUROP\u00cb, AJO JE TI\u201d"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/128664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=128664"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/128664\/revisions"}],"predecessor-version":[{"id":128668,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/128664\/revisions\/128668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/128669"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=128664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=128664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=128664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}