{"id":127695,"date":"2017-02-08T00:00:00","date_gmt":"2017-02-08T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/"},"modified":"2024-07-30T19:21:34","modified_gmt":"2024-07-30T19:21:34","slug":"eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/","title":{"rendered":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC"},"content":{"rendered":"<p>\n\t<strong><img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-4.jpg\" style=\"width: 315px; height: 230px; float: left;\" \/><\/strong><strong>Bujanoc \u2013<\/strong> Me planifikimin e renovimit t\u00eb sall\u00ebs s\u00eb vog\u00ebl t\u00eb Sht\u00ebpis\u00eb s\u00eb Kultur\u00ebs \u201cVuk Karaxhiq\u201d n\u00eb Bujanoc, e cila do t\u00eb kryhet deri n\u00eb fund t\u00eb vitit, do t\u00eb zgjidhet problemi me vite t\u00eb t\u00ebra t\u00eb dritareve n\u00eb kulm t\u00eb cilat l\u00ebshojn\u00eb ujin e shiut.<\/p>\n<p>\n\t\u201eNj\u00ebri nd\u00ebr prioritetet e investimeve p\u00ebr vitin 2017, \u00ebsht\u00eb renovimi i sall\u00ebs s\u00eb vog\u00ebl. \u00cbsht\u00eb planifikuar q\u00eb t`i ndrrojm\u00eb dritaret n\u00eb kulm dhe n\u00eb k\u00ebt\u00eb m\u00ebnyr\u00eb ta ndalojm\u00eb ndikimin e d\u00ebmsh\u00ebm t\u00eb shiut dhe lag\u00ebshtis\u00eb n\u00eb hap\u00ebsirat e mbrendshme. P\u00ebrve\u00e7 k\u00ebsaj, \u00ebsht\u00eb parapar\u00eb edhe ndrrimi i dyshemes\u00eb, si dhe lyerja e sall\u00ebs dhe hap\u00ebsir\u00ebs s\u00eb zyr\u00ebs\u201d, tha drejtori i Sht\u00ebpis\u00eb s\u00eb Kultur\u00ebs n\u00eb Bujanoc, Jetmir Ismaili.<\/p>\n<p>\n\tP\u00ebrve\u00e7 k\u00ebsaj, udh\u00ebheq\u00ebsia e k\u00ebtij insitucioni publik ka planifikuar edhe ndrrimin e ulluqeve n\u00eb pjes\u00ebn perendimore t\u00eb nd\u00ebrtes\u00ebs.<\/p>\n<p>\n\t<strong>Burimi: Bujanova\u00e7ke dhe Trupit Koordinues\u00a0<\/strong><\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bujanoc \u2013\u00a0Me planifikimin e renovimit t\u00eb sall\u00ebs s\u00eb vog\u00ebl t\u00eb Sht\u00ebpis\u00eb s\u00eb Kultur\u00ebs \u201cVuk Karaxhiq\u201d n\u00eb Bujanoc, e cila do t\u00eb kryhet deri n\u00eb fund t\u00eb vitit, do t\u00eb zgjidhet problemi me vite t\u00eb t\u00ebra t\u00eb dritareve n\u00eb kulm t\u00eb cilat l\u00ebshojn\u00eb ujin e shiut.<\/p>\n","protected":false},"author":1,"featured_media":127700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-127695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Bujanoc \u2013\u00a0Me planifikimin e renovimit t\u00eb sall\u00ebs s\u00eb vog\u00ebl t\u00eb Sht\u00ebpis\u00eb s\u00eb Kultur\u00ebs \u201cVuk Karaxhiq\u201d n\u00eb Bujanoc, e cila do t\u00eb kryhet deri n\u00eb fund t\u00eb vitit, do t\u00eb zgjidhet problemi me vite t\u00eb t\u00ebra t\u00eb dritareve n\u00eb kulm t\u00eb cilat l\u00ebshojn\u00eb ujin e shiut.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-08T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:21:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC\",\"datePublished\":\"2017-02-08T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:21:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1486553425_news_pic_080217_2-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/\",\"name\":\"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1486553425_news_pic_080217_2-5.jpg\",\"datePublished\":\"2017-02-08T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:21:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1486553425_news_pic_080217_2-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1486553425_news_pic_080217_2-5.jpg\",\"width\":315,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/","og_locale":"sq_AL","og_type":"article","og_title":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Bujanoc \u2013\u00a0Me planifikimin e renovimit t\u00eb sall\u00ebs s\u00eb vog\u00ebl t\u00eb Sht\u00ebpis\u00eb s\u00eb Kultur\u00ebs \u201cVuk Karaxhiq\u201d n\u00eb Bujanoc, e cila do t\u00eb kryhet deri n\u00eb fund t\u00eb vitit, do t\u00eb zgjidhet problemi me vite t\u00eb t\u00ebra t\u00eb dritareve n\u00eb kulm t\u00eb cilat l\u00ebshojn\u00eb ujin e shiut.","og_url":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2017-02-08T00:00:00+00:00","article_modified_time":"2024-07-30T19:21:34+00:00","og_image":[{"width":315,"height":230,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC","datePublished":"2017-02-08T00:00:00+00:00","dateModified":"2024-07-30T19:21:34+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/"},"wordCount":265,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/","url":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/","name":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg","datePublished":"2017-02-08T00:00:00+00:00","dateModified":"2024-07-30T19:21:34+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1486553425_news_pic_080217_2-5.jpg","width":315,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/eshte-renovuar-salla-e-vogel-e-shtepise-se-kultures-ne-bujanoc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"\u00cbSHT\u00cb RENOVUAR SALLA E VOG\u00cbL E SHT\u00cbPIS\u00cb S\u00cb KULTUR\u00cbS N\u00cb BUJANOC"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/127695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=127695"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/127695\/revisions"}],"predecessor-version":[{"id":127699,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/127695\/revisions\/127699"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/127700"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=127695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=127695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=127695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}