{"id":125372,"date":"2017-07-28T00:00:00","date_gmt":"2017-07-28T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/"},"modified":"2024-07-30T19:17:38","modified_gmt":"2024-07-30T19:17:38","slug":"eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/","title":{"rendered":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE"},"content":{"rendered":"<p>\n\t<strong><img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-4.jpg\" style=\"width: 315px; height: 230px; float: left;\" \/><\/strong><strong>Beograd \u2013<\/strong> Zyra p\u00ebr Bashk\u00ebpunim me Shoq\u00ebrin\u00eb Civile, si Pik\u00eb Nacionale p\u00ebr Kontakt p\u00ebr Programin e UE-s\u00eb \u201cEuropa p\u00ebr qytetear\u00ebt dhe qytetaret\u201d, njofton t\u00eb gjith\u00eb t\u00eb interesuarit se \u00ebsht\u00eb hapur ftesa e dyt\u00eb vjetore p\u00ebr dor\u00ebzimin e projekteve n\u00eb kuad\u00ebr t\u00eb masave t\u00eb Binjak\u00ebzimit t\u00eb Qyteteve dhe Rrjetit t\u00eb Qyteteve.<\/p>\n<p>\n\tFtesa \u00ebsht\u00eb hapur deri <strong>m\u00eb 1 shtator 2017, n\u00eb ora 12.<\/strong><\/p>\n<p>\n\tP\u00ebr m\u00eb shum\u00eb informacioni klikoni n\u00eb liknun: <a href=\"https:\/\/eacea.ec.europa.eu\/europe-for-citizens\/funding_en\">https:\/\/eacea.ec.europa.eu\/europe-for-citizens\/funding_en<\/a>\u00a0\u00a0\u00a0<\/p>\n<p>\n\t<strong>Burimi: Zyra p\u00ebr Bashk\u00ebpunim me Shoq\u00ebrin\u00eb Civile dhe Trupi Koordinues<\/strong><\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beograd \u2013\u00a0Zyra p\u00ebr Bashk\u00ebpunim me Shoq\u00ebrin\u00eb Civile, si Pik\u00eb Nacionale p\u00ebr Kontakt p\u00ebr Programin e UE-s\u00eb \u201cEuropa p\u00ebr qytetear\u00ebt dhe qytetaret\u201d, njofton t\u00eb gjith\u00eb t\u00eb interesuarit se \u00ebsht\u00eb hapur ftesa e dyt\u00eb vjetore p\u00ebr dor\u00ebzimin e projekteve n\u00eb kuad\u00ebr t\u00eb masave t\u00eb Binjak\u00ebzimit t\u00eb Qyteteve dhe Rrjetit t\u00eb Qyteteve.<\/p>\n","protected":false},"author":1,"featured_media":125377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-125372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Beograd \u2013\u00a0Zyra p\u00ebr Bashk\u00ebpunim me Shoq\u00ebrin\u00eb Civile, si Pik\u00eb Nacionale p\u00ebr Kontakt p\u00ebr Programin e UE-s\u00eb \u201cEuropa p\u00ebr qytetear\u00ebt dhe qytetaret\u201d, njofton t\u00eb gjith\u00eb t\u00eb interesuarit se \u00ebsht\u00eb hapur ftesa e dyt\u00eb vjetore p\u00ebr dor\u00ebzimin e projekteve n\u00eb kuad\u00ebr t\u00eb masave t\u00eb Binjak\u00ebzimit t\u00eb Qyteteve dhe Rrjetit t\u00eb Qyteteve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-28T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE\",\"datePublished\":\"2017-07-28T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:17:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/\"},\"wordCount\":165,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1501233970_news_pic_28072017_4-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/\",\"name\":\"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1501233970_news_pic_28072017_4-5.jpg\",\"datePublished\":\"2017-07-28T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:17:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1501233970_news_pic_28072017_4-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1501233970_news_pic_28072017_4-5.jpg\",\"width\":315,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/","og_locale":"sq_AL","og_type":"article","og_title":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Beograd \u2013\u00a0Zyra p\u00ebr Bashk\u00ebpunim me Shoq\u00ebrin\u00eb Civile, si Pik\u00eb Nacionale p\u00ebr Kontakt p\u00ebr Programin e UE-s\u00eb \u201cEuropa p\u00ebr qytetear\u00ebt dhe qytetaret\u201d, njofton t\u00eb gjith\u00eb t\u00eb interesuarit se \u00ebsht\u00eb hapur ftesa e dyt\u00eb vjetore p\u00ebr dor\u00ebzimin e projekteve n\u00eb kuad\u00ebr t\u00eb masave t\u00eb Binjak\u00ebzimit t\u00eb Qyteteve dhe Rrjetit t\u00eb Qyteteve.","og_url":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2017-07-28T00:00:00+00:00","article_modified_time":"2024-07-30T19:17:38+00:00","og_image":[{"width":315,"height":230,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE","datePublished":"2017-07-28T00:00:00+00:00","dateModified":"2024-07-30T19:17:38+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/"},"wordCount":165,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/","url":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/","name":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg","datePublished":"2017-07-28T00:00:00+00:00","dateModified":"2024-07-30T19:17:38+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1501233970_news_pic_28072017_4-5.jpg","width":315,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/eshte-hapur-ftesa-ne-kuader-te-programit-te-europes-per-qytetare-dhe-qytetare-binjakezimi-i-qyteteve-dhe-rrejti-i-qyteteve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"\u00cbSHT\u00cb HAPUR FTESA N\u00cb KUAD\u00cbR T\u00cb PROGRAMIT T\u00cb EUROP\u00cbS P\u00cbR QYTETAR\u00cb DHE QYTETARE: BINJAK\u00cbZIMI I QYTETEVE DHE RREJTI I QYTETEVE"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=125372"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125372\/revisions"}],"predecessor-version":[{"id":125376,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125372\/revisions\/125376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/125377"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=125372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=125372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=125372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}