{"id":125164,"date":"2017-08-15T00:00:00","date_gmt":"2017-08-15T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/"},"modified":"2024-07-30T19:17:16","modified_gmt":"2024-07-30T19:17:16","slug":"stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/","title":{"rendered":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb"},"content":{"rendered":"<p>\n\t<strong><img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-4.jpg\" style=\"width: 315px; height: 230px; float: left;\" \/><\/strong><\/p>\n<p>\n\t<strong>Beograd \u2013<\/strong> Kryetari i Trupit Koordinues i Qeveris\u00eb s\u00eb Republik\u00ebs s\u00eb Serbis\u00eb p\u00ebr komunat Preshev\u00eb, Bujanoc dhe Medvegj\u00eb, Zoran Stankoviq, ka deklaruar se dialogu n\u00eb mes Prishtin\u00ebs dhe Beogradit zhvillohet pavarsisht dhe se \u00e7\u00ebshtja e udh\u00ebheqja e vetqeverisjes lokale n\u00eb jug t\u00eb Serbis\u00eb nuk mund t\u00eb shihet n\u00eb konstekstin e bisedimeve n\u00eb Bruksel.<\/p>\n<p>\n\t\u201eNuk egziston asnj\u00eb paralele n\u00eb mes zgjidhjes s\u00eb problemeve t\u00eb serb\u00ebve n\u00eb Kosov\u00eb dhe Metohi dhe zgjidhjes s\u00eb problemeve t\u00eb funskionimit t\u00eb vetqeverisjes lokale n\u00eb tri komunat n\u00eb jugun e Serbis\u00eb \u2013 Preshev\u00eb, Bujanoc dhe Medvegj\u00eb, sepse kjo \u00ebsht\u00eb definuar me ligj dhe se shteti i Serbis\u00eb n\u00eb kufijt\u00eb e mund\u00ebsive dhe aft\u00ebsive t\u00eb saj b\u00ebn\u00eb gjith\u00e7ka q\u00eb k\u00ebrkesat e udh\u00ebheq\u00ebsis\u00eb n\u00eb k\u00ebto tri komuna t\u00eb zgjidhen\u201d, deklaroi Zoran Stankoviq p\u00ebr Radio Europa e Lir\u00eb.<\/p>\n<p>\n\tNga ana tjet\u00ebr, kryetari i komun\u00ebs s\u00eb Bujanocit Shaip Kamberi ka vler\u00ebsuar se mardh\u00ebnia e Serbis\u00eb ndaj shqiptar\u00ebve n\u00eb jug \u00ebsht\u00eb e r\u00ebnd\u00ebsishme p\u00ebr pozit\u00ebn e serb\u00ebve n\u00eb Kosov\u00eb dhe Metohi.<\/p>\n<p>\n\tShaip Kamberi tha se \u201cnormalizimi i mardh\u00ebnieve n\u00eb mes Beogradit dhe Prishtin\u00ebs do t\u00eb duhej q\u00eb t\u00eb kaloj p\u00ebrmes Preshev\u00ebs dhe Bujanocit\u201d.<\/p>\n<p>\n\t\u201cMardh\u00ebnia e shtetit ndaj shqiptar\u00ebve t\u00eb cil\u00ebt jetojn\u00eb n\u00eb k\u00ebt\u00eb territor \u00ebsht\u00eb ndihma m\u00eb e mir\u00eb t\u00eb cil\u00ebn Serbia ua ofron serb\u00ebve n\u00eb Kosov\u00eb dhe Metohi. Kjo \u00ebsht\u00eb e r\u00ebnd\u00ebsishme edhe p\u00ebr stabilitetin e rajonit ton\u00eb, por edhe p\u00ebr stabilizimin e mardh\u00ebnieve shqiptaro-serbe n\u00eb t\u00eb ardhmen\u201d, tha Kamberi p\u00ebr Radio Europa e Lir\u00eb.\u00a0<\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beograd \u2013\u00a0Kryetari i Trupit Koordinues i Qeveris\u00eb s\u00eb Republik\u00ebs s\u00eb Serbis\u00eb p\u00ebr komunat Preshev\u00eb, Bujanoc dhe Medvegj\u00eb, Zoran Stankoviq, ka deklaruar se dialogu n\u00eb mes Prishtin\u00ebs dhe Beogradit zhvillohet pavarsisht dhe se \u00e7\u00ebshtja e udh\u00ebheqja e vetqeverisjes lokale n\u00eb jug t\u00eb Serbis\u00eb nuk mund t\u00eb shihet n\u00eb konstekstin e bisedimeve n\u00eb Bruksel.<\/p>\n","protected":false},"author":1,"featured_media":125169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-125164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Beograd \u2013\u00a0Kryetari i Trupit Koordinues i Qeveris\u00eb s\u00eb Republik\u00ebs s\u00eb Serbis\u00eb p\u00ebr komunat Preshev\u00eb, Bujanoc dhe Medvegj\u00eb, Zoran Stankoviq, ka deklaruar se dialogu n\u00eb mes Prishtin\u00ebs dhe Beogradit zhvillohet pavarsisht dhe se \u00e7\u00ebshtja e udh\u00ebheqja e vetqeverisjes lokale n\u00eb jug t\u00eb Serbis\u00eb nuk mund t\u00eb shihet n\u00eb konstekstin e bisedimeve n\u00eb Bruksel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-15T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:17:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb\",\"datePublished\":\"2017-08-15T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:17:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/\"},\"wordCount\":410,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1502790891_news_pic_15082017_1-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/\",\"name\":\"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1502790891_news_pic_15082017_1-5.jpg\",\"datePublished\":\"2017-08-15T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:17:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1502790891_news_pic_15082017_1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1502790891_news_pic_15082017_1-5.jpg\",\"width\":315,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/","og_locale":"sq_AL","og_type":"article","og_title":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Beograd \u2013\u00a0Kryetari i Trupit Koordinues i Qeveris\u00eb s\u00eb Republik\u00ebs s\u00eb Serbis\u00eb p\u00ebr komunat Preshev\u00eb, Bujanoc dhe Medvegj\u00eb, Zoran Stankoviq, ka deklaruar se dialogu n\u00eb mes Prishtin\u00ebs dhe Beogradit zhvillohet pavarsisht dhe se \u00e7\u00ebshtja e udh\u00ebheqja e vetqeverisjes lokale n\u00eb jug t\u00eb Serbis\u00eb nuk mund t\u00eb shihet n\u00eb konstekstin e bisedimeve n\u00eb Bruksel.","og_url":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2017-08-15T00:00:00+00:00","article_modified_time":"2024-07-30T19:17:16+00:00","og_image":[{"width":315,"height":230,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb","datePublished":"2017-08-15T00:00:00+00:00","dateModified":"2024-07-30T19:17:16+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/"},"wordCount":410,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/","url":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/","name":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg","datePublished":"2017-08-15T00:00:00+00:00","dateModified":"2024-07-30T19:17:16+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1502790891_news_pic_15082017_1-5.jpg","width":315,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/stankoviq-nuk-ka-paralele-ne-mes-serbeve-ne-kosove-e-metohi-dhe-shqiptareve-ne-jugun-e-serbise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"STANKOVIQ: NUK KA PARALELE N\u00cb MES SERB\u00cbVE N\u00cb KOSOV\u00cb E METOHI DHE SHQIPTAR\u00cbVE N\u00cb JUGUN E SERBIS\u00cb"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=125164"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125164\/revisions"}],"predecessor-version":[{"id":125168,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/125164\/revisions\/125168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/125169"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=125164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=125164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=125164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}