{"id":121539,"date":"2018-06-04T00:00:00","date_gmt":"2018-06-04T00:00:00","guid":{"rendered":"http:\/\/kt.printandscreen.rs\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/"},"modified":"2024-07-30T19:11:01","modified_gmt":"2024-07-30T19:11:01","slug":"ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj","status":"publish","type":"post","link":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/","title":{"rendered":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ"},"content":{"rendered":"<p>\n\t<strong><img decoding=\"async\" alt=\"\" src=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-4.jpg\" style=\"width: 315px; height: 230px; float: left;\" \/><\/strong><strong>Bujanoc \u2013<\/strong> N\u00eb dy shkolla t\u00eb mesme n\u00eb Bujanoc, ku m\u00ebsimet zhvillohen n\u00eb gjuh\u00ebn serbe dhe shqipe, ka vende p\u00ebr 330 nx\u00ebn\u00ebs t\u00eb cil\u00ebt e kan\u00eb p\u00ebrfunduar shkoll\u00ebn fillore.<\/p>\n<p>\n\tSipas portalit Titulli.com, n\u00eb shkoll\u00ebn \u201eSezai Suroi\u201c ka vend p\u00ebr 210 nx\u00ebn\u00ebs t\u00eb ri t\u00eb shkollave t\u00eb mesme, nd\u00ebrsa 120 n\u00eb shkoll\u00ebn &quot;Sveti Sava&quot;.<\/p>\n<p>\n\tDriton Rexhepi, kryeshef i Drejtoris\u00eb Komunale p\u00ebr Arsim, tha se vet\u00ebqeverisja lokale kishte nd\u00ebrmarr\u00eb t\u00eb gjitha hapat e nevojshme p\u00ebr regjistrim n\u00eb vitin shkollor 2018\/19. vit.<\/p>\n<p>\n\tMinistria e Arsimit shkoll\u00ebs &quot;Sezai Surroi&quot; i ka miratuar drejtimet e p\u00ebrgjithshme t\u00eb gjimnazit, si dhe inxhinieri ekonomike, mjek\u00ebsore, mekanike dhe elektrike, nd\u00ebrsa shkolla po k\u00ebrkon miratimin p\u00ebr hapjen e shkall\u00ebs s\u00eb tret\u00eb p\u00ebr drejtimin elektricist.<\/p>\n<p>\n\tN\u00eb shkoll\u00ebn &quot;Sveti Sava&quot; ka 120 vende p\u00ebr drejtimet: administrator financiar, mot\u00ebr medicinale\/edukator, teknik i automjeteve motorike, kuzhinier, kamerier dhe \u00ebmb\u00ebltorist.<\/p>\n<p>\n\tProvimi pranues mbahet n\u00eb muajin qershor, nd\u00ebrsa sipas statistikave t\u00eb Departamentit t\u00eb Arsimit n\u00eb komun\u00ebn e Bujanocit, vitin akamemik 2017\/18 n\u00eb gjuh\u00ebn serbe e ndjekin 2,073 nx\u00ebn\u00ebs t\u00eb shkollave fillore dhe t\u00eb mesme dhe 2759 n\u00eb gjuh\u00ebn shqipe.<\/p>\n<p>\n\t<strong>Burimi: Bujanova\u00e7ke dhe Trupi Koordinues<\/strong><\/p>\n<p>\n\t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bujanoc \u2013\u00a0N\u00eb dy shkolla t\u00eb mesme n\u00eb Bujanoc, ku m\u00ebsimet zhvillohen n\u00eb gjuh\u00ebn serbe dhe shqipe, ka vende p\u00ebr 330 nx\u00ebn\u00ebs t\u00eb cil\u00ebt e kan\u00eb p\u00ebrfunduar shkoll\u00ebn fillore.<\/p>\n","protected":false},"author":1,"featured_media":121544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-121539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"og:description\" content=\"Bujanoc -\u00a0N\u00eb dy shkolla t\u00eb mesme n\u00eb Bujanoc, ku m\u00ebsimet zhvillohen n\u00eb gjuh\u00ebn serbe dhe shqipe, ka vende p\u00ebr 330 nx\u00ebn\u00ebs t\u00eb cil\u00ebt e kan\u00eb p\u00ebrfunduar shkoll\u00ebn fillore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/\" \/>\n<meta property=\"og:site_name\" content=\"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-04T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-30T19:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"315\" \/>\n\t<meta property=\"og:image:height\" content=\"230\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ktmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:site\" content=\"@kt_gov\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ktmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/\"},\"author\":{\"name\":\"ktmin\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\"},\"headline\":\"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ\",\"datePublished\":\"2018-06-04T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:11:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/\"},\"wordCount\":299,\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1528104509_news_pic_04062018_1-5.jpg\",\"articleSection\":[\"Lajme\"],\"inLanguage\":\"sq-AL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/\",\"name\":\"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1528104509_news_pic_04062018_1-5.jpg\",\"datePublished\":\"2018-06-04T00:00:00+00:00\",\"dateModified\":\"2024-07-30T19:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1528104509_news_pic_04062018_1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1528104509_news_pic_04062018_1-5.jpg\",\"width\":315,\"height\":230},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u041f\u043e\u0447\u0435\u0442\u043d\u0430\",\"item\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#website\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\"},\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kt.gov.rs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#organization\",\"name\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\",\"alternateName\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"contentUrl\":\"https:\\\/\\\/kt.gov.rs\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/koord2.jpg\",\"width\":640,\"height\":480,\"caption\":\"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a\"},\"image\":{\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SluzbaKoordinacionogTelaVladeRepublikeSrbije\",\"https:\\\/\\\/x.com\\\/kt_gov\",\"https:\\\/\\\/www.youtube.com\\\/@koordinacionotelo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/kt.gov.rs\\\/#\\\/schema\\\/person\\\/e426459ddb4173309103390602694571\",\"name\":\"ktmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g\",\"caption\":\"ktmin\"},\"sameAs\":[\"https:\\\/\\\/kt.gov.rs\"],\"url\":\"https:\\\/\\\/kt.gov.rs\\\/sq\\\/author\\\/ktmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/","og_locale":"sq_AL","og_type":"article","og_title":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","og_description":"Bujanoc -\u00a0N\u00eb dy shkolla t\u00eb mesme n\u00eb Bujanoc, ku m\u00ebsimet zhvillohen n\u00eb gjuh\u00ebn serbe dhe shqipe, ka vende p\u00ebr 330 nx\u00ebn\u00ebs t\u00eb cil\u00ebt e kan\u00eb p\u00ebrfunduar shkoll\u00ebn fillore.","og_url":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/","og_site_name":"Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","article_publisher":"https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","article_published_time":"2018-06-04T00:00:00+00:00","article_modified_time":"2024-07-30T19:11:01+00:00","og_image":[{"width":315,"height":230,"url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg","type":"image\/jpeg"}],"author":"ktmin","twitter_card":"summary_large_image","twitter_creator":"@kt_gov","twitter_site":"@kt_gov","twitter_misc":{"Written by":"ktmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#article","isPartOf":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/"},"author":{"name":"ktmin","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571"},"headline":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ","datePublished":"2018-06-04T00:00:00+00:00","dateModified":"2024-07-30T19:11:01+00:00","mainEntityOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/"},"wordCount":299,"publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg","articleSection":["Lajme"],"inLanguage":"sq-AL"},{"@type":"WebPage","@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/","url":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/","name":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ - Republika e S\u00ebrbis\u00eb Trupi Koordinues p\u00ebr komunat Bujanoc, Preshev\u00eb dhe Medvegj\u00eb","isPartOf":{"@id":"https:\/\/kt.gov.rs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#primaryimage"},"image":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#primaryimage"},"thumbnailUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg","datePublished":"2018-06-04T00:00:00+00:00","dateModified":"2024-07-30T19:11:01+00:00","breadcrumb":{"@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#breadcrumb"},"inLanguage":"sq-AL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/"]}]},{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#primaryimage","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/07\/1528104509_news_pic_04062018_1-5.jpg","width":315,"height":230},{"@type":"BreadcrumbList","@id":"https:\/\/kt.gov.rs\/sq\/ne-shkollat-e-mesme-ne-bujanoc-ka-vend-per-330-nxenes-te-rinj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u041f\u043e\u0447\u0435\u0442\u043d\u0430","item":"https:\/\/kt.gov.rs\/sq\/"},{"@type":"ListItem","position":2,"name":"N\u00cb SHKOLLAT E MESME N\u00cb BUJANOC KA VEND P\u00cbR 330 NX\u00cbN\u00cbS T\u00cb RINJ"}]},{"@type":"WebSite","@id":"https:\/\/kt.gov.rs\/#website","url":"https:\/\/kt.gov.rs\/","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","description":"","publisher":{"@id":"https:\/\/kt.gov.rs\/#organization"},"alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kt.gov.rs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kt.gov.rs\/#organization","name":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a","alternateName":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e","url":"https:\/\/kt.gov.rs\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/","url":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","contentUrl":"https:\/\/kt.gov.rs\/wp-content\/uploads\/2024\/12\/koord2.jpg","width":640,"height":480,"caption":"\u041a\u043e\u043e\u0440\u0434\u0438\u043d\u0430\u0446\u0438\u043e\u043d\u043e \u0442\u0435\u043b\u043e \u0412\u043b\u0430\u0434\u0435 \u0420\u0435\u043f\u0443\u0431\u043b\u0438\u043a\u0435 \u0421\u0440\u0431\u0438\u0458\u0435 \u0437\u0430 \u043e\u043f\u0448\u0442\u0438\u043d\u0435 \u041f\u0440\u0435\u0448\u0435\u0432\u043e, \u0411\u0443\u0458\u0430\u043d\u043e\u0432\u0430\u0446 \u0438 \u041c\u0435\u0434\u0432\u0435\u0452a"},"image":{"@id":"https:\/\/kt.gov.rs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SluzbaKoordinacionogTelaVladeRepublikeSrbije","https:\/\/x.com\/kt_gov","https:\/\/www.youtube.com\/@koordinacionotelo"]},{"@type":"Person","@id":"https:\/\/kt.gov.rs\/#\/schema\/person\/e426459ddb4173309103390602694571","name":"ktmin","image":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3985c961109853010c3fbc7ba30365bfba5db3dd6c525831d9c595c7525a615a?s=96&d=mm&r=g","caption":"ktmin"},"sameAs":["https:\/\/kt.gov.rs"],"url":"https:\/\/kt.gov.rs\/sq\/author\/ktmin\/"}]}},"_links":{"self":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/121539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/comments?post=121539"}],"version-history":[{"count":1,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/121539\/revisions"}],"predecessor-version":[{"id":121543,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/posts\/121539\/revisions\/121543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media\/121544"}],"wp:attachment":[{"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/media?parent=121539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/categories?post=121539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kt.gov.rs\/sq\/wp-json\/wp\/v2\/tags?post=121539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}